{"id":2171,"date":"2020-03-20T23:05:06","date_gmt":"2020-03-20T22:05:06","guid":{"rendered":"http:\/\/bergerlebnisse.com\/estate\/settimane-di-arrampicata\/klst-03\/"},"modified":"2025-09-05T17:14:47","modified_gmt":"2025-09-05T15:14:47","slug":"klst-03","status":"publish","type":"page","link":"https:\/\/bergerlebnisse.com\/it\/estate\/settimane-di-arrampicata\/klst-03\/","title":{"rendered":"klst-03"},"content":{"rendered":"\n<h1>\n\t\t\tArrampicata Brenta per intenditori\t<\/h1>\n\t<b>02.-05.07.2026<br \/>\n<\/b>\n<strong>Servizi: <\/strong>Visita guidata, 3 x mezza pensione.<br \/>\n<strong>Partecipanti: <\/strong>3-5 persone<strong><br \/>\nPrezzo:<\/strong> \u20ac 780 a persona<br \/>\n<strong>Tempo di percorso<\/strong>: 5-6 ore per giorno<br \/>\n<b>Condizione<\/b>: buone condizioni, sicurezza e strabilio\n<p><strong>Suggerimento:<\/strong> L&#8217;attrezzatura mancante viene fornita gratuitamente!<\/p>\n<p>&nbsp;<\/p>\n<strong>Programma:<br \/>\n<\/strong>Chi non li conosce, il pi\u00f9 bello, spesso esposto via ferrata nel Gruppo Brenta. Un vero Eldorado per via ferrata conquistatori. Questa settimana attraversiamo il gruppo Brenta da rifugio a rifugio via ferrata.<strong><br \/>\n<\/strong>\n<b>Ferate<\/b><br \/>\nvia Bocchettasentiero al Rifugio Tosa 2.445 m.\n<p>Sentiero Orsi prosegue sulla Tuckettscharte e sul Sentiero delle Bocchette Alte. Pernottamento al rifugio Alimonta 3.600 m.<\/p>\n<p>Sentiero delle Bocchette Centrali con pernottamento al Capannone Tosa 2.445 m.<\/p>\n\n\t\t\t<a href=\"https:\/\/bergerlebnisse.com\/it\/richiesta-prenotazione\/\" target=\"_self\">\n\t\t\t\t\t\t\tRichiesta \/ Prenotazione\n\t\t\t\t\t<\/a>\n<h2>\n\t\t\tSUGGERIMENTO: Buoni regalo\t<\/h2>\n\t<h4>Regalare un&#8217;esperienza indimenticabile<\/h4>\nTutti i tour offerti possono anche essere forniti come voucher di avventura.<br \/>\nBasta selezionare il tour e la data desiderati e ti invieremo il tuo voucher regalo personale in PDF, che puoi semplicemente stampare da solo!\n\t\t\t<a href=\"http:\/\/bergerlebnisse.com\/it\/buono-regalo\/\" target=\"_self\">\n\t\t\t\t\t\tOrdinare un voucher\n\t\t\t\t\t<\/a>\n\t<h2>\n\t\t\t\tI NOSTRI PARTNER\n\t\t\t<\/h2>\n\t\t\t\t<a href=\"http:\/\/www.gasthaus-sonneck.it\/\"  target=\"_blank\" rel=\"noopener\"  itemprop=\"url\">\n\t\t\t\t<img decoding=\"async\" src=\"http:\/\/bergerlebnisse.com\/wp-content\/uploads\/2020\/02\/Logo-Sonneck.jpg\" alt=\"Logo Sonneck\" itemprop=\"image\" title=\"Logo Sonneck\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t\t\t\t<\/a>\n\t\t\t\t<a href=\"http:\/\/hochseilgarten-laas.it\"  target=\"_blank\" rel=\"noopener\"  itemprop=\"url\">\n\t\t\t\t<img decoding=\"async\" src=\"http:\/\/bergerlebnisse.com\/wp-content\/uploads\/2020\/02\/Logo-Hochseilgarten.jpg\" alt=\"Logo corde alte corso\" itemprop=\"image\" title=\"Logo corde alte corso\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t\t\t\t<\/a>\n\t\t\t\t<a href=\"https:\/\/www.schweitzer-getraenke.it\/\"  target=\"_blank\" rel=\"noopener\"  itemprop=\"url\">\n\t\t\t\t<img decoding=\"async\" src=\"http:\/\/bergerlebnisse.com\/wp-content\/uploads\/2020\/02\/Logo-Schweizer.jpg\" alt=\"Logo-Svizzero\" itemprop=\"image\" title=\"Logo-Svizzero\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t\t\t\t<\/a>\n\t\t\t\t<a href=\"https:\/\/www.saegemuehle.it\/de\/\"  target=\"_blank\" rel=\"noopener\"  itemprop=\"url\">\n\t\t\t\t<img decoding=\"async\" src=\"http:\/\/bergerlebnisse.com\/wp-content\/uploads\/2020\/02\/Logo-S\u00e4gem\u00fchle.jpg\" alt=\"Segheria logo\" itemprop=\"image\" title=\"Segheria logo\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t\t\t\t<\/a>\n\t\t\t\t<a href=\"https:\/\/www.bergfrieden.com\"  target=\"_blank\" rel=\"noopener\"  itemprop=\"url\">\n\t\t\t\t<img decoding=\"async\" src=\"http:\/\/bergerlebnisse.com\/wp-content\/uploads\/2020\/02\/Bergfrieden-Logo.jpg\" alt=\"Bergfrieden-Logo\" itemprop=\"image\" title=\"Bergfrieden-Logo\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t\t\t\t<\/a>\n\t\t\t\t<a href=\"https:\/\/www.odler.it\/pizzeria-odler-laas\/\"  target=\"_blank\" rel=\"noopener\"  itemprop=\"url\">\n\t\t\t\t<img decoding=\"async\" src=\"http:\/\/bergerlebnisse.com\/wp-content\/uploads\/2020\/02\/logo_kl.jpg\" alt=\"logo_kl\" itemprop=\"image\" title=\"logo_kl\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t\t\t\t<\/a>\n\n","protected":false},"excerpt":{"rendered":"<p>Arrampicata Brenta per intenditori 02.-05.07.2026 Servizi: Visita guidata, 3 x mezza pensione. Partecipanti: 3-5 persone Prezzo: \u20ac 780 a persona Tempo di percorso: 5-6 ore per giorno Condizione: buone condizioni, sicurezza e strabilio Suggerimento: L&#8217;attrezzatura mancante viene fornita gratuitamente! &nbsp; Programma: Chi non li conosce, il pi\u00f9 bello, spesso esposto via ferrata nel Gruppo Brenta.&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":2166,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-2171","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Settimana dell&#039;arrampicata BRENTA un sogno per gli amanti dell&#039;arrampicata<\/title>\n<meta name=\"description\" content=\"Un vero Eldorado per via ferrata conquistatori. Questa settimana attraversiamo il gruppo Brenta da rifugio a rifugio via ferrata.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bergerlebnisse.com\/it\/estate\/settimane-di-arrampicata\/klst-03\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Settimana dell&#039;arrampicata BRENTA un sogno per gli amanti dell&#039;arrampicata\" \/>\n<meta property=\"og:description\" content=\"Un vero Eldorado per via ferrata conquistatori. Questa settimana attraversiamo il gruppo Brenta da rifugio a rifugio via ferrata.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bergerlebnisse.com\/it\/estate\/settimane-di-arrampicata\/klst-03\/\" \/>\n<meta property=\"og:site_name\" content=\"Bergerlebnisse\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/skischuletrafoi\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-05T15:14:47+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/bergerlebnisse.com\/wp-content\/uploads\/2020\/02\/Logo-Sonneck.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bergerlebnisse.com\/it\/estate\/settimane-di-arrampicata\/klst-03\/\",\"url\":\"https:\/\/bergerlebnisse.com\/it\/estate\/settimane-di-arrampicata\/klst-03\/\",\"name\":\"Settimana dell'arrampicata BRENTA un sogno per gli amanti dell'arrampicata\",\"isPartOf\":{\"@id\":\"https:\/\/bergerlebnisse.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/bergerlebnisse.com\/it\/estate\/settimane-di-arrampicata\/klst-03\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/bergerlebnisse.com\/it\/estate\/settimane-di-arrampicata\/klst-03\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/bergerlebnisse.com\/wp-content\/uploads\/2020\/02\/Logo-Sonneck.jpg\",\"datePublished\":\"2020-03-20T22:05:06+00:00\",\"dateModified\":\"2025-09-05T15:14:47+00:00\",\"description\":\"Un vero Eldorado per via ferrata conquistatori. Questa settimana attraversiamo il gruppo Brenta da rifugio a rifugio via ferrata.\",\"breadcrumb\":{\"@id\":\"https:\/\/bergerlebnisse.com\/it\/estate\/settimane-di-arrampicata\/klst-03\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bergerlebnisse.com\/it\/estate\/settimane-di-arrampicata\/klst-03\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/bergerlebnisse.com\/it\/estate\/settimane-di-arrampicata\/klst-03\/#primaryimage\",\"url\":\"http:\/\/bergerlebnisse.com\/wp-content\/uploads\/2020\/02\/Logo-Sonneck.jpg\",\"contentUrl\":\"http:\/\/bergerlebnisse.com\/wp-content\/uploads\/2020\/02\/Logo-Sonneck.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bergerlebnisse.com\/it\/estate\/settimane-di-arrampicata\/klst-03\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/bergerlebnisse.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ESTATE\",\"item\":\"https:\/\/bergerlebnisse.com\/it\/estate\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SETTIMANE DI ARRAMPICATA\",\"item\":\"https:\/\/bergerlebnisse.com\/it\/estate\/settimane-di-arrampicata\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"klst-03\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/bergerlebnisse.com\/it\/#website\",\"url\":\"https:\/\/bergerlebnisse.com\/it\/\",\"name\":\"Skischule Trafoi\",\"description\":\"Erlebe die S\u00fcdtiroler Berge mit einem Experten\",\"publisher\":{\"@id\":\"https:\/\/bergerlebnisse.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/bergerlebnisse.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/bergerlebnisse.com\/it\/#organization\",\"name\":\"Skischule Trafoi\",\"url\":\"https:\/\/bergerlebnisse.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/bergerlebnisse.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Skischule Trafoi\"},\"image\":{\"@id\":\"https:\/\/bergerlebnisse.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/skischuletrafoi\",\"https:\/\/www.instagram.com\/skischule_trafoi\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Settimana dell'arrampicata BRENTA un sogno per gli amanti dell'arrampicata","description":"Un vero Eldorado per via ferrata conquistatori. Questa settimana attraversiamo il gruppo Brenta da rifugio a rifugio via ferrata.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bergerlebnisse.com\/it\/estate\/settimane-di-arrampicata\/klst-03\/","og_locale":"it_IT","og_type":"article","og_title":"Settimana dell'arrampicata BRENTA un sogno per gli amanti dell'arrampicata","og_description":"Un vero Eldorado per via ferrata conquistatori. Questa settimana attraversiamo il gruppo Brenta da rifugio a rifugio via ferrata.","og_url":"https:\/\/bergerlebnisse.com\/it\/estate\/settimane-di-arrampicata\/klst-03\/","og_site_name":"Bergerlebnisse","article_publisher":"https:\/\/www.facebook.com\/skischuletrafoi","article_modified_time":"2025-09-05T15:14:47+00:00","og_image":[{"url":"http:\/\/bergerlebnisse.com\/wp-content\/uploads\/2020\/02\/Logo-Sonneck.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bergerlebnisse.com\/it\/estate\/settimane-di-arrampicata\/klst-03\/","url":"https:\/\/bergerlebnisse.com\/it\/estate\/settimane-di-arrampicata\/klst-03\/","name":"Settimana dell'arrampicata BRENTA un sogno per gli amanti dell'arrampicata","isPartOf":{"@id":"https:\/\/bergerlebnisse.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bergerlebnisse.com\/it\/estate\/settimane-di-arrampicata\/klst-03\/#primaryimage"},"image":{"@id":"https:\/\/bergerlebnisse.com\/it\/estate\/settimane-di-arrampicata\/klst-03\/#primaryimage"},"thumbnailUrl":"http:\/\/bergerlebnisse.com\/wp-content\/uploads\/2020\/02\/Logo-Sonneck.jpg","datePublished":"2020-03-20T22:05:06+00:00","dateModified":"2025-09-05T15:14:47+00:00","description":"Un vero Eldorado per via ferrata conquistatori. Questa settimana attraversiamo il gruppo Brenta da rifugio a rifugio via ferrata.","breadcrumb":{"@id":"https:\/\/bergerlebnisse.com\/it\/estate\/settimane-di-arrampicata\/klst-03\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bergerlebnisse.com\/it\/estate\/settimane-di-arrampicata\/klst-03\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/bergerlebnisse.com\/it\/estate\/settimane-di-arrampicata\/klst-03\/#primaryimage","url":"http:\/\/bergerlebnisse.com\/wp-content\/uploads\/2020\/02\/Logo-Sonneck.jpg","contentUrl":"http:\/\/bergerlebnisse.com\/wp-content\/uploads\/2020\/02\/Logo-Sonneck.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/bergerlebnisse.com\/it\/estate\/settimane-di-arrampicata\/klst-03\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/bergerlebnisse.com\/it\/"},{"@type":"ListItem","position":2,"name":"ESTATE","item":"https:\/\/bergerlebnisse.com\/it\/estate\/"},{"@type":"ListItem","position":3,"name":"SETTIMANE DI ARRAMPICATA","item":"https:\/\/bergerlebnisse.com\/it\/estate\/settimane-di-arrampicata\/"},{"@type":"ListItem","position":4,"name":"klst-03"}]},{"@type":"WebSite","@id":"https:\/\/bergerlebnisse.com\/it\/#website","url":"https:\/\/bergerlebnisse.com\/it\/","name":"Skischule Trafoi","description":"Erlebe die S\u00fcdtiroler Berge mit einem Experten","publisher":{"@id":"https:\/\/bergerlebnisse.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bergerlebnisse.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/bergerlebnisse.com\/it\/#organization","name":"Skischule Trafoi","url":"https:\/\/bergerlebnisse.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/bergerlebnisse.com\/it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Skischule Trafoi"},"image":{"@id":"https:\/\/bergerlebnisse.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/skischuletrafoi","https:\/\/www.instagram.com\/skischule_trafoi\/"]}]}},"_links":{"self":[{"href":"https:\/\/bergerlebnisse.com\/it\/wp-json\/wp\/v2\/pages\/2171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bergerlebnisse.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bergerlebnisse.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bergerlebnisse.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bergerlebnisse.com\/it\/wp-json\/wp\/v2\/comments?post=2171"}],"version-history":[{"count":10,"href":"https:\/\/bergerlebnisse.com\/it\/wp-json\/wp\/v2\/pages\/2171\/revisions"}],"predecessor-version":[{"id":7114,"href":"https:\/\/bergerlebnisse.com\/it\/wp-json\/wp\/v2\/pages\/2171\/revisions\/7114"}],"up":[{"embeddable":true,"href":"https:\/\/bergerlebnisse.com\/it\/wp-json\/wp\/v2\/pages\/2166"}],"wp:attachment":[{"href":"https:\/\/bergerlebnisse.com\/it\/wp-json\/wp\/v2\/media?parent=2171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}